{"id":3,"date":"2025-09-24T08:28:56","date_gmt":"2025-09-24T08:28:56","guid":{"rendered":"https:\/\/torneadossallobente.rkinformatika.online\/?page_id=3"},"modified":"2025-09-24T12:27:35","modified_gmt":"2025-09-24T12:27:35","slug":"politicas-de-cookies","status":"publish","type":"page","link":"https:\/\/torneadossallobente.com\/eu\/politicas-de-cookies\/","title":{"rendered":"Cookie politikak"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c91ac3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c91ac3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36c5e30\" data-id=\"36c5e30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeeeec2 elementor-widget elementor-widget-text-editor\" data-id=\"eeeeec2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"western\">POLITICA DE COOKIES<\/h1><p class=\"western\" align=\"justify\"><span lang=\"es-ES-u-co-trad\">En cumplimiento con lo dispuesto en el art\u00edculo 22.2 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, esta p\u00e1gina web le informa, en esta secci\u00f3n, sobre la pol\u00edtica de recogida y tratamiento de cookies.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Dicho articulo establece que los prestadores de servicios podr\u00e1n utilizar dispositivos de almacenamiento y recuperaci\u00f3n de datos en equipos terminales de los destinatarios, a condici\u00f3n d e que los mismos hayan dado su consentimiento despu\u00e9s de que e les haya facilitado la informaci\u00f3n clara y completa su utilizaci\u00f3n, en particular, sobre los fines del tratamiento de los datos, con arreglo a lo dispuesto en el Reglamento (UE) 2016\/679, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>QU\u00c9 SON LAS COOKIES<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario. El navegador del usuario memoriza cookies en el disco duro solamente durante la sesi\u00f3n actual ocupando un espacio de memoria m\u00ednimo y no perjudicando al ordenador. Las cookies no contienen ninguna clase de informaci\u00f3n personal espec\u00edfica, y la mayor\u00eda de las mismas se borran del disco duro al finalizar la sesi\u00f3n de navegador (las denominadas cookies de sesi\u00f3n).<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">La mayor\u00eda de los navegadores aceptan como est\u00e1ndar a las cookies y, con independencia de las mismas, permiten o impiden en los ajustes de seguridad las cookies temporales o memorizadas.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Sin su expreso consentimiento, mediante la activaci\u00f3n de las cookies en su navegador, <\/span><span lang=\"es-ES-u-co-trad\"><b>SALLOBENTE Torneados <\/b><\/span><span lang=\"es-ES-u-co-trad\">no enlazar\u00e1 en las cookies los datos memorizados con sus datos personales.<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\"><b>TIPOS DE COOKIES<\/b><\/span><\/p><p><span lang=\"es-ES-u-co-trad\">Las cookies se agrupan a grandes rasgos en las siguientes categor\u00edas:<\/span><\/p><ul><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies propias:<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">\u00a0aque\u0301llas que se envi\u0301an al equipo terminal del usuario desde un equipo o dominio gestionado por el propio editor y desde el que se presta el servicio solicitado por el usuario.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies de terceros:<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">\u00a0aque\u0301llas que se envi\u0301an al equipo terminal del usuario desde un equipo o dominio que no es gestionado por el editor, sino por otra entidad que trata los datos obtenidos trave\u0301s de las cookies.<\/span><\/p><\/li><\/ul><p><span lang=\"es-ES-u-co-trad\">En el caso de que las cookies sean instaladas desde un equipo o dominio gestionado por el propio editor pero la informacio\u0301n que se recoja mediante e\u0301stas sea gestionada por un tercero, no pueden ser consideradas como cookies propias.<br \/>Existe tambie\u0301n una segunda clasificacio\u0301n segu\u0301n el plazo de tiempo que permanecen almacenadas en el navegador del cliente, pudiendo tratarse de:<\/span><\/p><ul><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>Tipos de cookies seg\u00fan el plazo de tiempo que permanecen activadas:<\/b><\/span><\/p><\/li><\/ul><ul><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies de sesi\u00f3n:<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">\u00a0Son un tipo de cookies dise\u00f1adas para recabar y almacenar datos mientras el usuario accede a una p\u00e1gina web. Se suelen emplear para almacenar informaci\u00f3n que solo interesa conservar para la prestaci\u00f3n del servicio solicitado por el usuario en una sola ocasi\u00f3n (p.e. una lista de productos adquiridos).<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies persistentes:<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">\u00a0Son un tipo de cookies en el que los datos siguen almacenados en el terminal y pueden ser accedidos y tratados durante un periodo definido por el responsable de la cookie, y que puede ir de unos minutos a varios a\u00f1os.<\/span><\/p><\/li><\/ul><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Por \u00faltimo, existe otra clasificaci\u00f3n con cinco tipos de cookies seg\u00fan la finalidad para la que se traten los datos obtenidos:<\/span><\/p><ul><li><p><span lang=\"es-ES-u-co-trad\"><b>Tipos de cookies seg\u00fan su finalidad:<br \/><\/b><\/span><\/p><\/li><\/ul><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Seg\u00fan la finalidad para la que se traten los datos obtenidos a trav\u00e9s de las cookies, podemos distinguir entre:<\/span><\/p><ul><li><p class=\"western\" align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies t\u00e9cnicas:\u00a0<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">Son aqu\u00e9llas que permiten al usuario la navegaci\u00f3n a trav\u00e9s de una p\u00e1gina web, plataforma o aplicaci\u00f3n y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan como, por ejemplo, controlar el tr\u00e1fico y la comunicaci\u00f3n de datos, identificar la sesi\u00f3n, acceder a partes de acceso restringido, recordar los elementos que integran un pedido, realizar el proceso de compra de un pedido, realizar la solicitud de inscripci\u00f3n o participaci\u00f3n en un evento, utilizar elementos de seguridad durante la navegaci\u00f3n, almacenar contenidos para la difusi\u00f3n de v\u00eddeos o sonido o compartir contenidos a trav\u00e9s de redes sociales.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies de personalizaci\u00f3n:<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">\u00a0Son aqu\u00e9llas que permiten al usuario acceder al servicio con algunas caracter\u00edsticas de car\u00e1cter general predefinidas en funci\u00f3n de una serie de criterios en el terminal del usuario como por ejemplo serian el idioma, el tipo de navegador a trav\u00e9s del cual accede al servicio, la configuraci\u00f3n regional desde donde accede al servicio, etc.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies de an\u00e1lisis:<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">\u00a0Son aqu\u00e9llas que permiten al responsable de las mismas, el seguimiento y an\u00e1lisis del comportamiento de los usuarios de los sitios web a los que est\u00e1n vinculadas. La informaci\u00f3n recogida mediante este tipo de cookies se utiliza en la medici\u00f3n de la actividad de los sitios web, aplicaci\u00f3n o plataforma y para la elaboraci\u00f3n de perfiles de navegaci\u00f3n de los usuarios de dichos sitios, aplicaciones y plataformas, con el fin de introducir mejoras en funci\u00f3n del an\u00e1lisis de los datos de uso que hacen los usuarios del servicio.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies publicitarias<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">: Son aqu\u00e9llas que permiten la gesti\u00f3n, de la forma m\u00e1s eficaz posible, de los espacios publicitarios de p\u00e1gina web desde la que se presta el servicio.<br \/>Cookies de publicidad comportamental: Son aqu\u00e9llas que permiten la gesti\u00f3n, de la forma m\u00e1s eficaz posible, de los espacios publicitarios en esta web. Estas cookies almacenan informaci\u00f3n del comportamiento de los usuarios obtenida a trav\u00e9s de la observaci\u00f3n continuada de sus h\u00e1bitos de navegaci\u00f3n, lo que permite desarrollar un perfil espec\u00edfico para mostrar publicidad en funci\u00f3n del mismo.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><u><b>Cookies de redes sociales externas:<\/b><\/u><\/span><span lang=\"es-ES-u-co-trad\">\u00a0se utilizan para que los visitantes puedan interactuar con el contenido de diferentes plataformas sociales (facebook, youtube, twitter, linkedIn, etc..) y que se generen u\u0301nicamente para los usuarios de dichas redes sociales. Las condiciones de utilizacio\u0301n de estas cookies y la informacio\u0301n recopilada se regula por la poli\u0301tica de privacidad de la plataforma social correspondiente.<\/span><\/p><\/li><\/ul><p class=\"western\"><span lang=\"es-ES-u-co-trad\"><b>COOKIES DE TERCEROS<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Algunas de las cookies incluidas en las categor\u00edas de cookies descritas anteriormente las almacenan terceros en su equipo cuando usted utiliza nuestra web. No tenemos control alguno sobre estas cookies o el modo en que las utilizan los terceros. Se utilizan para permitir al tercero prestarnos un servicio, por ejemplo, de an\u00e1lisis.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>El Usuario acepta expresamente, por la utilizaci\u00f3n de este Site,\u00a0el tratamiento de la informaci\u00f3n\u00a0recabada en la forma y con los fines anteriormente mencionados.<\/b><\/span><span lang=\"es-ES-u-co-trad\">\u00a0Y asimismo reconoce conocer la posibilidad de rechazar el tratamiento de\u00a0tales datos o informaci\u00f3n\u00a0rechazando el uso de Cookies mediante la selecci\u00f3n de la configuraci\u00f3n apropiada a tal fin en su navegador. Si bien esta opci\u00f3n de bloqueo de Cookies en su navegador puede no permitirle el uso pleno de todas las funcionalidades del Website.<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\"><b>COOKIES QUE UTILIZAMOS EN ESTE SITIO WEB<\/b><\/span><span lang=\"es-ES-u-co-trad\"><b><br \/><\/b><\/span><span lang=\"es-ES-u-co-trad\">A continuaci\u00f3n se identifican las cookies que est\u00e1n siendo utilizadas en este portal, as\u00ed como su tipolog\u00eda y funci\u00f3n:<\/span><\/p><table width=\"566\" cellspacing=\"0\" cellpadding=\"7\"><tbody><tr><td bgcolor=\"#595959\" width=\"174\"><p class=\"western\" align=\"center\"><span lang=\"es-ES-u-co-trad\"><b>COOKIE<br \/>(Y PROVEEDOR)<\/b><\/span><\/p><\/td><td bgcolor=\"#595959\" width=\"175\"><p class=\"western\" align=\"center\"><span lang=\"es-ES-u-co-trad\"><b>DURACI\u00d3N<\/b><\/span><\/p><\/td><td bgcolor=\"#595959\" width=\"174\"><p class=\"western\" align=\"center\"><span lang=\"es-ES-u-co-trad\"><b>DESCRIPCI\u00d3N<\/b><\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">__cfduid (notin.es)<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Sesi\u00f3n<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Publicidad<\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">personalization_id (twitter.com)<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Sesi\u00f3n<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Twitter<\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Facebook<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Publicidad, estad\u00edsticas y mediciones<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Coloca Cookies en el ordenador o dispositivo y recibe la informaci\u00f3n almacenada en ellas cuando utilizas o visitas servicios prestados por otras empresas que utilizan los servicios de Facebook.<\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">_ga (Google)<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">2 a\u00f1os<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Se usa para distinguir a los usuarios.<\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">_gid (Google)<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">24 horas<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Se usa para distinguir a los usuarios.<\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">_gat (Google)<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">1\u00a0minuto<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Se usa para limitar el porcentaje de solicitudes. Si has implementado Google Analytics mediante Google\u00a0Tag\u00a0Manager, esta cookie se llamar\u00e1 _dc_gtm_&lt;property-id&gt;.<\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">_gali (Google)<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">30s<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Atribuci\u00f3n de enlace mejorada.<\/span><\/p><\/td><\/tr><tr valign=\"bottom\"><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">_unam (SHARETHIS)<\/span><\/p><\/td><td width=\"175\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Persistente<\/span><\/p><\/td><td width=\"174\"><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\">Su finalidad es cuantificar el n\u00famero de Usuarios que comparten un determinado contenido y cu\u00e1ntas p\u00e1ginas web son visitadas a ra\u00edz de esa acci\u00f3n.<\/span><\/p><\/td><\/tr><\/tbody><\/table><p class=\"western\" align=\"justify\"><span lang=\"es-ES-u-co-trad\">Utilizamos Google Analytics, un servicio de anal\u00edtica web desarrollada por Google, que permite la medici\u00f3n y an\u00e1lisis de la navegaci\u00f3n en las p\u00e1ginas web. En su navegador podr\u00e1 observar cookies de este servicio. Seg\u00fan la tipolog\u00eda anterior se trata de cookies propias, de sesi\u00f3n y de an\u00e1lisis.<\/span><\/p><p class=\"western\" align=\"justify\"><span lang=\"es-ES-u-co-trad\">A trav\u00e9s de la anal\u00edtica web se obtiene informaci\u00f3n relativa al n\u00famero de usuarios que acceden a la web, el n\u00famero de p\u00e1ginas vistas, la frecuencia y repetici\u00f3n de las visitas, su duraci\u00f3n, el navegador utilizado, el operador que presta el servicio, el idioma, el terminal que utiliza y la ciudad a la que est\u00e1 asignada su direcci\u00f3n IP. Informaci\u00f3n que posibilita un mejor y m\u00e1s apropiado servicio por parte de este portal.<\/span><\/p><p class=\"western\" align=\"justify\"><span lang=\"es-ES-u-co-trad\">Para garantizar el anonimato, Google convertir\u00e1 su informaci\u00f3n en an\u00f3nima truncando la direcci\u00f3n IP antes de almacenarla, de forma que Google Analytics no se usa para localizar o recabar informaci\u00f3n personal identificable de los visitantes del sitio. Google solo podr\u00e1 enviar la informaci\u00f3n recabada por Google Analytics a terceros cuanto est\u00e9 legalmente obligado a ello. Con arreglo a las condiciones de prestaci\u00f3n del servicio de Google Analytics, Google no asociar\u00e1 su direcci\u00f3n IP a ning\u00fan otro dato conservado por Google.<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\"><b>\u00bfPUEDO RECHAZAR O EXCLUIR LA RECEPCION DE COOKIES?<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Si desea rechazar o excluir la recepci\u00f3n de cookies puede hacer lo siguiente:<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Borre las cookies de su navegador. La mayor\u00eda de los navegadores le permiten evitar el almacenamiento en su equipo de todas las cookies o de algunas en lo sucesivo. Para m\u00e1s informaci\u00f3n sobre c\u00f3mo borrar o deshabilitar las cookies desde su navegador, utilice el men\u00fa de \u201cayuda\u201d del navegador.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Si s\u00f3lo quiere rechazar todas o algunas de las cookies de terceros, deber\u00e1 visitar directamente la web del tercero pertinente para gestionar las cookies que \u00e9ste almacena en su equipo. Consulte nuestra secci\u00f3n \u201cCookies de terceros\u201d<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Tenga en cuenta que el hecho de deshabilitar las cookies puede afectar a las prestaciones de esta web.<\/span><\/p><p><span lang=\"es-ES-u-co-trad\"><b>COMO ELIMINAR LAS COOKIES DEL NAVEGADOR<\/b><\/span><b><\/b><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\"><b>Chrome<\/b><\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\">1. Selecciona el icono de Herramientas<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\">2. Haz clic en Configuraci\u00f3n.<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\">3. Haz clic en Mostrar Opciones Avanzadas.<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\">4. En la secci\u00f3n \u00abPrivacidad\u00bb haz clic en Configuraci\u00f3n de contenido.<\/span><\/p><p class=\"western\">\u2022\u00a0<span lang=\"es-ES-u-co-trad\">Eliminar cookies: Haz clic en Todas las cookies y los datos de sitios\u2026<\/span><\/p><p class=\"western\">\u2022\u00a0<span lang=\"es-ES-u-co-trad\">No permitir que se almacenen cookies.<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\">5. Haz clic en Eliminar datos de navegaci\u00f3n (vaciar la Cach\u00e9).<\/span><\/p><p class=\"western\"><span lang=\"es-ES-u-co-trad\">6. Cierra y reinicia el navegador. Para m\u00e1s informaci\u00f3n sobre Chrome pulse aqu\u00ed:\u00a0<\/span><u><a href=\"http:\/\/support.google.com\/chrome\/answer\/95647?hl=es\"><span lang=\"es-ES-u-co-trad\">http:\/\/support.google.com\/chrome\/answer\/95647?hl=es<\/span><\/a><\/u><\/p><p><span lang=\"es-ES-u-co-trad\"><b>Internet Explorer. Versi\u00f3n 11<\/b><\/span><span lang=\"es-ES-u-co-trad\"><br \/>1. Selecciona Herramientas | Opciones de Internet.<br \/>2. Haz clic en la ficha General.<br \/>3. En la secci\u00f3n \u00abHistorial de exploraci\u00f3n\u00bb, haz clic en Eliminar el historial de exploraci\u00f3n al salir.<br \/>4. Seleccionar Eliminar archivos.<br \/>5. Seleccionar Eliminar cookies.<br \/>6. Haz clic en Eliminar.<br \/>7. Haz clic en Aceptar.<br \/>8. Cierra y reinicia el navegador.<br \/>Para m\u00e1s informaci\u00f3n sobre Internet Explorer pulse aqu\u00ed:\u00a0<\/span><u><a href=\"http:\/\/windows.microsoft.com\/es-419\/windows7\/how-to-manage-cookies-in-internet-explorer-9\"><span lang=\"es-ES-u-co-trad\">http:\/\/windows.microsoft.com\/es-419\/windows7\/how-to-manage-cookies-in-internet-explorer-9<\/span><\/a><\/u><\/p><p><span lang=\"es-ES-u-co-trad\"><b>Firefox. Versi\u00f3n 18<\/b><\/span><span lang=\"es-ES-u-co-trad\"><br \/>1. Selecciona Firefox | Historial | Limpiar el historial reciente.<br \/>2. Al lado de \u00abDetalles\u00bb, haz clic en la flecha hacia abajo.<br \/>3. Selecciona las siguientes casillas de verificaci\u00f3n: Cookies, Cach\u00e9, Inicios de sesi\u00f3n activos<br \/>4. Usando el \u00abIntervalo de tiempo para borrar\u00bb en el men\u00fa desplegable, selecciona Todo.<br \/>5. Haz clic en Borrar ahora.<br \/>6. Cierra y reinicia el navegador.<br \/>Puede aceptar o rechazar las cookies individualmente en las Preferencias de Firefox, en la secci\u00f3n Historial disponible en Herramientas &gt; Opciones &gt; Privacidad.<br \/>Para m\u00e1s informaci\u00f3n sobre Mozilla Firefox pulse aqu\u00ed: https:\/\/www.mozilla.org\/es-ES\/privacy\/websites\/#cookies<\/span><\/p><p class=\"western\" align=\"left\"><span lang=\"es-ES-u-co-trad\"><b>Safari Versi\u00f3n 5.1<\/b><\/span><span lang=\"es-ES-u-co-trad\"><br \/>1. Selecciona el icono de Safari \/ Editar | Restaurar Safari.<br \/>2. Selecciona las siguientes casillas de verificaci\u00f3n: Borrar el historial, Eliminar todos los datos de sitio web<br \/>3. Haz clic en Restablecer.<br \/>4. Cierra y reinicia el navegador.<br \/>Para m\u00e1s informaci\u00f3n sobre Safari pulse aqu\u00ed:\u00a0<\/span><u><a href=\"http:\/\/support.apple.com\/kb\/PH5042\"><span lang=\"es-ES-u-co-trad\">http:\/\/support.apple.com\/kb\/PH5042<\/span><\/a><\/u><\/p><p><span lang=\"es-ES-u-co-trad\"><b>Opera<\/b><\/span><span lang=\"es-ES-u-co-trad\"><br \/>Opciones \u2013 Avanzado \u2013 Cookies.<br \/>Las opciones de cookies controlan el modo en que Opera los maneja y por lo tanto su aceptaci\u00f3n o rechazo.<br \/>Para m\u00e1s informaci\u00f3n sobre \u00d3pera pulse aqu\u00ed: https:\/\/help.opera.com\/en\/latest\/security-and-privacy\/#clearBrowsingData<\/span><\/p><p><span lang=\"es-ES-u-co-trad\"><b>Otros navegadores<\/b><\/span><span lang=\"es-ES-u-co-trad\"><br \/>Consulte la documentaci\u00f3n del navegador que tenga instalado.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>POLITICA DE COOKIES En cumplimiento con lo dispuesto en el art\u00edculo 22.2 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, esta p\u00e1gina web le informa, en esta secci\u00f3n, sobre la pol\u00edtica de recogida y tratamiento de cookies. Dicho articulo establece que los prestadores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edticas de Cookies - SALLOBENTE Torneados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/torneadossallobente.com\/eu\/politicas-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edticas de Cookies - SALLOBENTE Torneados\" \/>\n<meta property=\"og:description\" content=\"POLITICA DE COOKIES En cumplimiento con lo dispuesto en el art\u00edculo 22.2 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, esta p\u00e1gina web le informa, en esta secci\u00f3n, sobre la pol\u00edtica de recogida y tratamiento de cookies. Dicho articulo establece que los prestadores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/torneadossallobente.com\/eu\/politicas-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"SALLOBENTE Torneados\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-24T12:27:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/politicas-de-cookies\\\/\",\"url\":\"https:\\\/\\\/torneadossallobente.com\\\/politicas-de-cookies\\\/\",\"name\":\"Pol\u00edticas de Cookies - SALLOBENTE Torneados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/#website\"},\"datePublished\":\"2025-09-24T08:28:56+00:00\",\"dateModified\":\"2025-09-24T12:27:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/politicas-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/torneadossallobente.com\\\/politicas-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/politicas-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/torneadossallobente.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edticas de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/#website\",\"url\":\"https:\\\/\\\/torneadossallobente.com\\\/\",\"name\":\"SALLOBENTE Torneados\",\"description\":\"SALLOBENTE Torneados\",\"publisher\":{\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/torneadossallobente.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/#organization\",\"name\":\"SALLOBENTE Torneados\",\"url\":\"https:\\\/\\\/torneadossallobente.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/torneadossallobente.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-logo1-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/torneadossallobente.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-logo1-removebg-preview.png\",\"width\":778,\"height\":259,\"caption\":\"SALLOBENTE Torneados\"},\"image\":{\"@id\":\"https:\\\/\\\/torneadossallobente.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edticas de Cookies - SALLOBENTE Torneados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/torneadossallobente.com\/eu\/politicas-de-cookies\/","og_locale":"en_US","og_type":"article","og_title":"Pol\u00edticas de Cookies - SALLOBENTE Torneados","og_description":"POLITICA DE COOKIES En cumplimiento con lo dispuesto en el art\u00edculo 22.2 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, esta p\u00e1gina web le informa, en esta secci\u00f3n, sobre la pol\u00edtica de recogida y tratamiento de cookies. Dicho articulo establece que los prestadores [&hellip;]","og_url":"https:\/\/torneadossallobente.com\/eu\/politicas-de-cookies\/","og_site_name":"SALLOBENTE Torneados","article_modified_time":"2025-09-24T12:27:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/torneadossallobente.com\/politicas-de-cookies\/","url":"https:\/\/torneadossallobente.com\/politicas-de-cookies\/","name":"Pol\u00edticas de Cookies - SALLOBENTE Torneados","isPartOf":{"@id":"https:\/\/torneadossallobente.com\/#website"},"datePublished":"2025-09-24T08:28:56+00:00","dateModified":"2025-09-24T12:27:35+00:00","breadcrumb":{"@id":"https:\/\/torneadossallobente.com\/politicas-de-cookies\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/torneadossallobente.com\/politicas-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/torneadossallobente.com\/politicas-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/torneadossallobente.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edticas de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/torneadossallobente.com\/#website","url":"https:\/\/torneadossallobente.com\/","name":"SALLOBENTE Torneados","description":"SALLOBENTE Torneados","publisher":{"@id":"https:\/\/torneadossallobente.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/torneadossallobente.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/torneadossallobente.com\/#organization","name":"SALLOBENTE Torneados","url":"https:\/\/torneadossallobente.com\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/torneadossallobente.com\/#\/schema\/logo\/image\/","url":"https:\/\/torneadossallobente.com\/wp-content\/uploads\/2025\/09\/cropped-logo1-removebg-preview.png","contentUrl":"https:\/\/torneadossallobente.com\/wp-content\/uploads\/2025\/09\/cropped-logo1-removebg-preview.png","width":778,"height":259,"caption":"SALLOBENTE Torneados"},"image":{"@id":"https:\/\/torneadossallobente.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":10,"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":313,"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/pages\/3\/revisions\/313"}],"wp:attachment":[{"href":"https:\/\/torneadossallobente.com\/eu\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}